{"id":11,"count":3,"description":"","link":"https:\/\/localglobals.com\/index.php\/category\/casino-onlina-ca\/","name":"casino onlina ca","slug":"casino-onlina-ca","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/localglobals.com\/index.php\/wp-json\/wp\/v2\/categories\/11"}],"collection":[{"href":"https:\/\/localglobals.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/localglobals.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/localglobals.com\/index.php\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}